{"id":18596,"date":"2024-12-31T03:28:52","date_gmt":"2024-12-31T03:28:52","guid":{"rendered":"https:\/\/www.cnshining.com\/?page_id=18596"},"modified":"2025-12-06T12:55:17","modified_gmt":"2025-12-06T12:55:17","slug":"frascos-de-bomba-de-locao-de-aluminio-de-120-ml-com-acabamento-de-gargalo-20-410","status":"publish","type":"page","link":"https:\/\/www.cnshining.com\/pt\/frascos-de-bomba-de-locao-de-aluminio-de-120-ml-com-acabamento-de-gargalo-20-410","title":{"rendered":"Frascos de lo\u00e7\u00e3o com bomba dosadora de alum\u00ednio de 120ml"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"18596\" class=\"elementor elementor-18596\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-17ec4b0 e-con-full e-flex e-con e-parent\" data-id=\"17ec4b0\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-75acb4c elementor-widget elementor-widget-text-editor\" data-id=\"75acb4c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>\t\t<div data-elementor-type=\"container\" data-elementor-id=\"34698\" class=\"elementor elementor-34698\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2dd6baa0 e-flex e-con-boxed e-con e-parent\" data-id=\"2dd6baa0\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4a6e77a8 elementor-icon-list--layout-inline elementor-align-center elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"4a6e77a8\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.cnshining.com\/pt\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-home\" viewbox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M280.37 148.26L96 300.11V464a16 16 0 0 0 16 16l112.06-.29a16 16 0 0 0 15.92-16V368a16 16 0 0 1 16-16h64a16 16 0 0 1 16 16v95.64a16 16 0 0 0 16 16.05L464 480a16 16 0 0 0 16-16V300L295.67 148.26a12.19 12.19 0 0 0-15.3 0zM571.6 251.47L488 182.56V44.05a12 12 0 0 0-12-12h-56a12 12 0 0 0-12 12v72.61L318.47 43a48 48 0 0 0-61 0L4.34 251.47a12 12 0 0 0-1.6 16.9l25.5 31A12 12 0 0 0 45.15 301l235.22-193.74a12.19 12.19 0 0 1 15.3 0L530.9 301a12 12 0 0 0 16.9-1.6l25.5-31a12 12 0 0 0-1.7-16.93z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Lar \/<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.cnshining.com\/pt\/mercado-de-garrafas-de-aluminio\/\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Garrafa de alum\u00ednio \/<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.cnshining.com\/pt\/produtos\/garrafa-de-aluminio-com-rosca\/\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Garrafa de alum\u00ednio com rosca \/<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2980fdf e-flex e-con-boxed e-con e-parent\" data-id=\"2980fdf\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-16956b9 e-con-full e-flex e-con e-child\" data-id=\"16956b9\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7e4ff88 elementor-skin-slideshow elementor-arrows-yes elementor-widget elementor-widget-media-carousel\" data-id=\"7e4ff88\" data-element_type=\"widget\" data-settings=\"{&quot;skin&quot;:&quot;slideshow&quot;,&quot;slideshow_slides_per_view&quot;:&quot;3&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;show_arrows&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"media-carousel.default\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.cnshining.com\/wp-content\/uploads\/2024\/12\/120ml-Aluminum-Lotion-Pump-Bottles-1.4.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"7e4ff88\" data-elementor-lightbox-title=\"120ml-Aluminum-Lotion-Pump-Bottles-1.4\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTg1OTgsInVybCI6Imh0dHBzOlwvXC93d3cuY25zaGluaW5nLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNFwvMTJcLzEyMG1sLUFsdW1pbnVtLUxvdGlvbi1QdW1wLUJvdHRsZXMtMS40LmpwZyIsInNsaWRlc2hvdyI6IjdlNGZmODgifQ%3D%3D\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"Frascos de lo\u00e7\u00e3o de alum\u00ednio com bomba dosadora de 120 ml - 1,4\" style=\"background-image: url(&#039;https:\/\/www.cnshining.com\/wp-content\/uploads\/2024\/12\/120ml-Aluminum-Lotion-Pump-Bottles-1.4.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.cnshining.com\/wp-content\/uploads\/2024\/12\/120ml-Aluminum-Lotion-Pump-Bottles-1.3.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"7e4ff88\" data-elementor-lightbox-title=\"120ml-Aluminum-Lotion-Pump-Bottles-1.3\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTg2MDIsInVybCI6Imh0dHBzOlwvXC93d3cuY25zaGluaW5nLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNFwvMTJcLzEyMG1sLUFsdW1pbnVtLUxvdGlvbi1QdW1wLUJvdHRsZXMtMS4zLmpwZyIsInNsaWRlc2hvdyI6IjdlNGZmODgifQ%3D%3D\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"Frascos de lo\u00e7\u00e3o de alum\u00ednio com bomba dosadora de 120 ml - 1,3\" style=\"background-image: url(&#039;https:\/\/www.cnshining.com\/wp-content\/uploads\/2024\/12\/120ml-Aluminum-Lotion-Pump-Bottles-1.3.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.cnshining.com\/wp-content\/uploads\/2024\/12\/120ml-Aluminum-Lotion-Pump-Bottles-1.1.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"7e4ff88\" data-elementor-lightbox-title=\"120ml-Aluminum-Lotion-Pump-Bottles-1.1\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTg2MDAsInVybCI6Imh0dHBzOlwvXC93d3cuY25zaGluaW5nLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNFwvMTJcLzEyMG1sLUFsdW1pbnVtLUxvdGlvbi1QdW1wLUJvdHRsZXMtMS4xLmpwZyIsInNsaWRlc2hvdyI6IjdlNGZmODgifQ%3D%3D\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"Frascos de alum\u00ednio com bomba dosadora para lo\u00e7\u00e3o, 120ml - 1.1\" style=\"background-image: url(&#039;https:\/\/www.cnshining.com\/wp-content\/uploads\/2024\/12\/120ml-Aluminum-Lotion-Pump-Bottles-1.1.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.cnshining.com\/wp-content\/uploads\/2024\/12\/120ml-Aluminum-Lotion-Pump-Bottles-1.2.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-slideshow=\"7e4ff88\" data-elementor-lightbox-title=\"120ml-Aluminum-Lotion-Pump-Bottles-1.2\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTg2MDEsInVybCI6Imh0dHBzOlwvXC93d3cuY25zaGluaW5nLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNFwvMTJcLzEyMG1sLUFsdW1pbnVtLUxvdGlvbi1QdW1wLUJvdHRsZXMtMS4yLmpwZyIsInNsaWRlc2hvdyI6IjdlNGZmODgifQ%3D%3D\">\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"Frascos de lo\u00e7\u00e3o de alum\u00ednio com bomba dosadora de 120 ml - 1,2\" style=\"background-image: url(&#039;https:\/\/www.cnshining.com\/wp-content\/uploads\/2024\/12\/120ml-Aluminum-Lotion-Pump-Bottles-1.2.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Anterior\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Pr\u00f3ximo\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-main-swiper swiper elementor-thumbnails-swiper swiper\" role=\"region region\" aria-roledescription=\"carousel carousel\" aria-label=\"Slides Slides\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"Frascos de lo\u00e7\u00e3o de alum\u00ednio com bomba dosadora de 120 ml - 1,4\" style=\"background-image: url(&#039;https:\/\/www.cnshining.com\/wp-content\/uploads\/2024\/12\/120ml-Aluminum-Lotion-Pump-Bottles-1.4.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"Frascos de lo\u00e7\u00e3o de alum\u00ednio com bomba dosadora de 120 ml - 1,3\" style=\"background-image: url(&#039;https:\/\/www.cnshining.com\/wp-content\/uploads\/2024\/12\/120ml-Aluminum-Lotion-Pump-Bottles-1.3.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"Frascos de alum\u00ednio com bomba dosadora para lo\u00e7\u00e3o, 120ml - 1.1\" style=\"background-image: url(&#039;https:\/\/www.cnshining.com\/wp-content\/uploads\/2024\/12\/120ml-Aluminum-Lotion-Pump-Bottles-1.1.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image\" role=\"img\" aria-label=\"Frascos de lo\u00e7\u00e3o de alum\u00ednio com bomba dosadora de 120 ml - 1,2\" style=\"background-image: url(&#039;https:\/\/www.cnshining.com\/wp-content\/uploads\/2024\/12\/120ml-Aluminum-Lotion-Pump-Bottles-1.2.jpg&#039;)\">\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-26d1c89 e-con-full e-flex e-con e-child\" data-id=\"26d1c89\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b7acedd elementor-widget elementor-widget-text-editor\" data-id=\"b7acedd\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<ul><li><strong>Material:<\/strong>99.7% 1070A Alum\u00ednio<\/li><li><strong>Volumes de enchimento:<\/strong>120 ml ou 4 on\u00e7as<\/li><li><strong>Formato dos ombros:<\/strong>Redondo<\/li><li><strong>Tamanhos dispon\u00edveis:<\/strong> \u03a635*150mm, \u03a640*120mm, \u03a645*100mm<\/li><li><strong>Op\u00e7\u00f5es de t\u00f3pico:<\/strong>18\/410, 20\/410, 24\/410, 28\/410<\/li><li><strong>Op\u00e7\u00f5es de cores:<\/strong>Escovado, Preto, Branco, etc.<\/li><li><strong>Revestimento interior:<\/strong>Revestimentos de poliimida \u00e0 base de poli\u00e9ster, revestimento interno livre de BPA; recomenda-se teste de compatibilidade.<\/li><li><strong>Sistemas de distribui\u00e7\u00e3o:<\/strong>Bomba de lo\u00e7\u00e3o<\/li><li><strong>Revestimentos exteriores:<\/strong>Base branca ou transparente<\/li><li><strong>T\u00e9cnicas de impress\u00e3o:<\/strong>Serigrafia, transfer\u00eancia t\u00e9rmica, impress\u00e3o offset<\/li><li><strong>Personaliza\u00e7\u00e3o de Impress\u00e3o:<\/strong>At\u00e9 9 cores com acabamento brilhante, semibrilhante e fosco.<\/li><li><strong>Quantidade m\u00ednima de encomenda:<\/strong>5.000 a 20.000 unidades, dependendo dos requisitos de impress\u00e3o.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bbb2da5 elementor-align-left elementor-invisible elementor-widget elementor-widget-button\" data-id=\"bbb2da5\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:800}\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjE0MTMyIiwidG9nZ2xlIjpmYWxzZX0%3D\" target=\"_blank\" rel=\"nofollow\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-circle-right\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8c137 0 248 111 248 248S393 504 256 504 8 393 8 256 119 8 256 8zm-28.9 143.6l75.5 72.4H120c-13.3 0-24 10.7-24 24v16c0 13.3 10.7 24 24 24h182.6l-75.5 72.4c-9.7 9.3-9.9 24.8-.4 34.3l11 10.9c9.4 9.4 24.6 9.4 33.9 0L404.3 273c9.4-9.4 9.4-24.6 0-33.9L271.6 106.3c-9.4-9.4-24.6-9.4-33.9 0l-11 10.9c-9.5 9.6-9.3 25.1.4 34.4z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Contate-nos<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f9be10f e-flex e-con-boxed e-con e-parent\" data-id=\"f9be10f\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-843a8e8 e-con-full e-flex e-con e-child\" data-id=\"843a8e8\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a26ee3b elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"a26ee3b\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Design ecol\u00f3gico e resistente<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-235e940 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"235e940\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>O <strong>Frasco de lo\u00e7\u00e3o com bomba dosadora em alum\u00ednio de 120ml<\/strong> \u00e9 uma solu\u00e7\u00e3o de embalagem projetada com foco em sustentabilidade e funcionalidade. Fabricada em alum\u00ednio 99.7% 1070A, esta garrafa n\u00e3o \u00e9 apenas leve, mas tamb\u00e9m excepcionalmente dur\u00e1vel. Sua natureza totalmente recicl\u00e1vel est\u00e1 alinhada com a crescente conscientiza\u00e7\u00e3o ambiental em pa\u00edses como Estados Unidos, Reino Unido e Austr\u00e1lia. Al\u00e9m de seus benef\u00edcios ecol\u00f3gicos, esta garrafa oferece prote\u00e7\u00e3o robusta para seu conte\u00fado, resguardando-o da luz, do ar e da umidade. A superf\u00edcie lisa e personaliz\u00e1vel permite uma personaliza\u00e7\u00e3o atraente da marca, tornando-a uma escolha pr\u00e1tica para empresas que buscam se destacar e, ao mesmo tempo, apoiar pr\u00e1ticas sustent\u00e1veis.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-79bb45f e-con-full e-flex e-con e-child\" data-id=\"79bb45f\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cc88a92 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"cc88a92\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:600}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.cnshining.com\/wp-content\/uploads\/2024\/12\/120ml-Aluminum-Lotion-Pump-Bottles-0.jpg\" class=\"attachment-large size-large wp-image-18603\" alt=\"Frascos de lo\u00e7\u00e3o de alum\u00ednio com bomba dosadora de 120 ml - 0\" srcset=\"https:\/\/www.cnshining.com\/wp-content\/uploads\/2024\/12\/120ml-Aluminum-Lotion-Pump-Bottles-0.jpg 1024w, https:\/\/www.cnshining.com\/wp-content\/uploads\/2024\/12\/120ml-Aluminum-Lotion-Pump-Bottles-0-300x300.jpg 300w, https:\/\/www.cnshining.com\/wp-content\/uploads\/2024\/12\/120ml-Aluminum-Lotion-Pump-Bottles-0-150x150.jpg 150w, https:\/\/www.cnshining.com\/wp-content\/uploads\/2024\/12\/120ml-Aluminum-Lotion-Pump-Bottles-0-768x768.jpg 768w, https:\/\/www.cnshining.com\/wp-content\/uploads\/2024\/12\/120ml-Aluminum-Lotion-Pump-Bottles-0-12x12.jpg 12w, https:\/\/www.cnshining.com\/wp-content\/uploads\/2024\/12\/120ml-Aluminum-Lotion-Pump-Bottles-0-600x600.jpg 600w, https:\/\/www.cnshining.com\/wp-content\/uploads\/2024\/12\/120ml-Aluminum-Lotion-Pump-Bottles-0-200x200.jpg 200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4d6619f e-flex e-con-boxed e-con e-parent\" data-id=\"4d6619f\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-16aa072 e-con-full e-flex e-con e-child\" data-id=\"16aa072\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4d7a642 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"4d7a642\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Tamanho perfeito e dimens\u00f5es pr\u00e1ticas<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-75ce1c5 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"75ce1c5\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>O <strong>120ml (4oz)<\/strong> capacidade deste <strong>Frasco de alum\u00ednio com bomba dosadora para lo\u00e7\u00e3o<\/strong> Isso a torna uma escolha ideal para uma variedade de formula\u00e7\u00f5es l\u00edquidas, encontrando um equil\u00edbrio entre portabilidade e volume suficiente. Dispon\u00edveis em tamanhos como \u03a635*150mm, \u03a640*120mm e \u03a645*100mm, os frascos s\u00e3o projetados com um formato de ombro arredondado que aprimora seu apelo ergon\u00f4mico e est\u00e9tico. Eles v\u00eam equipados com op\u00e7\u00f5es de rosca como 18\/410, 20\/410, 24\/410 e 28\/410, garantindo compatibilidade com diferentes sistemas de dosagem, incluindo bombas dosadoras de lo\u00e7\u00e3o. Essas especifica\u00e7\u00f5es cuidadosamente pensadas atendem \u00e0s diversas necessidades da ind\u00fastria.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fe632f8 e-flex e-con-boxed e-con e-parent\" data-id=\"fe632f8\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f69c44f e-con-full e-flex e-con e-child\" data-id=\"f69c44f\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-da8e13a elementor-widget elementor-widget-image\" data-id=\"da8e13a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2202\" height=\"893\" src=\"https:\/\/www.cnshining.com\/wp-content\/uploads\/2024\/12\/120ml-aluminum-Lotion-Pump-bottle-NECKS.png\" class=\"attachment-full size-full wp-image-18592\" alt=\"Gargalo de frasco de lo\u00e7\u00e3o de alum\u00ednio de 120 ml com bomba dosadora\" srcset=\"https:\/\/www.cnshining.com\/wp-content\/uploads\/2024\/12\/120ml-aluminum-Lotion-Pump-bottle-NECKS.png 2202w, https:\/\/www.cnshining.com\/wp-content\/uploads\/2024\/12\/120ml-aluminum-Lotion-Pump-bottle-NECKS-300x122.png 300w, https:\/\/www.cnshining.com\/wp-content\/uploads\/2024\/12\/120ml-aluminum-Lotion-Pump-bottle-NECKS-1024x415.png 1024w, https:\/\/www.cnshining.com\/wp-content\/uploads\/2024\/12\/120ml-aluminum-Lotion-Pump-bottle-NECKS-768x311.png 768w, https:\/\/www.cnshining.com\/wp-content\/uploads\/2024\/12\/120ml-aluminum-Lotion-Pump-bottle-NECKS-1536x623.png 1536w, https:\/\/www.cnshining.com\/wp-content\/uploads\/2024\/12\/120ml-aluminum-Lotion-Pump-bottle-NECKS-2048x831.png 2048w, https:\/\/www.cnshining.com\/wp-content\/uploads\/2024\/12\/120ml-aluminum-Lotion-Pump-bottle-NECKS-18x7.png 18w, https:\/\/www.cnshining.com\/wp-content\/uploads\/2024\/12\/120ml-aluminum-Lotion-Pump-bottle-NECKS-600x243.png 600w\" sizes=\"(max-width: 2202px) 100vw, 2202px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Frasco de alum\u00ednio com bomba dosadora para lo\u00e7\u00e3o, 120 ml (4 oz)<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-af5e150 e-flex e-con-boxed e-con e-parent\" data-id=\"af5e150\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-584e0e5 e-con-full e-flex e-con e-child\" data-id=\"584e0e5\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2d0fb7b elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"2d0fb7b\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Revestimentos avan\u00e7ados e acabamentos personaliz\u00e1veis<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9ae981d elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"9ae981d\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>O interior do <strong>Frasco de alum\u00ednio de 120 ml<\/strong> \u00e9 revestido com materiais de alta qualidade, como resina ep\u00f3xi, resina fen\u00f3lica ou resina poliamida-imida. Esses revestimentos, livres de BPA e pr\u00f3prios para contato com alimentos, oferecem excepcional resist\u00eancia \u00e0 corros\u00e3o, garantindo que o conte\u00fado permane\u00e7a seguro e livre de contamina\u00e7\u00e3o. Dispon\u00edveis em acabamentos amarelo-dourado ou transparente, esses revestimentos atendem aos padr\u00f5es da FDA e da LFGB (<a href=\"https:\/\/www.cnshining.com\/pt\/certificados\/\">certifica\u00e7\u00f5es<\/a>O exterior da garrafa pode ser personalizado com acabamentos como pintura, verniz, texturas escovadas ou apar\u00eancias brilhantes, semibrilhantes e foscas. Para adicionar um toque pessoal, as empresas podem optar por serigrafia, impress\u00e3o por transfer\u00eancia t\u00e9rmica ou impress\u00e3o offset. Explore nossas op\u00e7\u00f5es.\u00a0<a href=\"https:\/\/www.cnshining.com\/pt\/impressao\/\">solu\u00e7\u00f5es de impress\u00e3o<\/a>\u00a0para mais pormenores.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-198010e e-con-full e-flex e-con e-child\" data-id=\"198010e\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-234987e e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"234987e\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_delay&quot;:400}\">\n\t\t<div class=\"elementor-element elementor-element-9874ef4 e-con-full e-flex e-con e-child\" data-id=\"9874ef4\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-eb1142a elementor-widget elementor-widget-image\" data-id=\"eb1142a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.cnshining.com\/wp-content\/uploads\/2024\/12\/aluminum-bottles-printing-1.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"aluminum-bottles-printing\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTgwOTEsInVybCI6Imh0dHBzOlwvXC93d3cuY25zaGluaW5nLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNFwvMTJcL2FsdW1pbnVtLWJvdHRsZXMtcHJpbnRpbmctMS5qcGcifQ%3D%3D\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1000\" height=\"477\" src=\"https:\/\/www.cnshining.com\/wp-content\/uploads\/2024\/12\/aluminum-bottles-printing-1.jpg\" class=\"attachment-large size-large wp-image-18091\" alt=\"impress\u00e3o de garrafas de alum\u00ednio\" srcset=\"https:\/\/www.cnshining.com\/wp-content\/uploads\/2024\/12\/aluminum-bottles-printing-1.jpg 1000w, https:\/\/www.cnshining.com\/wp-content\/uploads\/2024\/12\/aluminum-bottles-printing-1-300x143.jpg 300w, https:\/\/www.cnshining.com\/wp-content\/uploads\/2024\/12\/aluminum-bottles-printing-1-768x366.jpg 768w, https:\/\/www.cnshining.com\/wp-content\/uploads\/2024\/12\/aluminum-bottles-printing-1-18x9.jpg 18w, https:\/\/www.cnshining.com\/wp-content\/uploads\/2024\/12\/aluminum-bottles-printing-1-600x286.jpg 600w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" title=\"\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d098f45 e-flex e-con-boxed e-con e-parent\" data-id=\"d098f45\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-6912de4 e-con-full e-flex e-con e-child\" data-id=\"6912de4\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e915d4a elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"e915d4a\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Aplica\u00e7\u00f5es em diversos setores<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-689e41d elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"689e41d\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>O <strong>Frascos de lo\u00e7\u00e3o com bomba dosadora de alum\u00ednio de 120ml<\/strong> S\u00e3o amplamente utilizadas na ind\u00fastria de cuidados pessoais e cosm\u00e9ticos para produtos como lo\u00e7\u00f5es para as m\u00e3os, cremes faciais e s\u00e9runs. Al\u00e9m disso, s\u00e3o muito valorizadas no setor de viagens e estilo de vida, oferecendo solu\u00e7\u00f5es de embalagem compactas e \u00e0 prova de vazamentos para produtos de cuidados com a pele e bem-estar. Sua combina\u00e7\u00e3o de durabilidade, portabilidade e apelo est\u00e9tico as torna uma excelente escolha em diversos setores.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-05ea5f0 e-flex e-con-boxed e-con e-parent\" data-id=\"05ea5f0\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-2f7b3a8 e-con-full e-flex e-con e-child\" data-id=\"2f7b3a8\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-32bf3c3 elementor-skin-carousel elementor-arrows-yes elementor-pagination-type-bullets elementor-pagination-position-outside elementor-widget elementor-widget-media-carousel\" data-id=\"32bf3c3\" data-element_type=\"widget\" data-settings=\"{&quot;lazyload&quot;:&quot;yes&quot;,&quot;space_between&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:13,&quot;sizes&quot;:[]},&quot;skin&quot;:&quot;carousel&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;show_arrows&quot;:&quot;yes&quot;,&quot;pagination&quot;:&quot;bullets&quot;,&quot;speed&quot;:500,&quot;autoplay&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;loop&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;space_between_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;space_between_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]}}\" data-widget_type=\"media-carousel.default\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-main-swiper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Slides\">\n\t\t\t\t<div class=\"swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"Frascos de alum\u00ednio com bomba dosadora para lo\u00e7\u00e3o - 0,1\" data-background=\"https:\/\/www.cnshining.com\/wp-content\/uploads\/2024\/12\/Aluminum-Lotion-Pump-Bottles-0.1.jpg\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"Frascos de alum\u00ednio com bomba dosadora para lo\u00e7\u00e3o - 0,2\" data-background=\"https:\/\/www.cnshining.com\/wp-content\/uploads\/2024\/12\/Aluminum-Lotion-Pump-Bottles-0.2.jpg\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-carousel-image swiper-lazy\" role=\"img\" aria-label=\"Frascos de alum\u00ednio com bomba dosadora para lo\u00e7\u00e3o - 0,3\" data-background=\"https:\/\/www.cnshining.com\/wp-content\/uploads\/2024\/12\/Aluminum-Lotion-Pump-Bottles-0.3.jpg\">\n\n\t\t\t\t\t\t\t<div class=\"swiper-lazy-preloader\"><\/div>\n\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\" aria-label=\"Anterior\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-left\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M646 125C629 125 613 133 604 142L308 442C296 454 292 471 292 487 292 504 296 521 308 533L604 854C617 867 629 875 646 875 663 875 679 871 692 858 704 846 713 829 713 812 713 796 708 779 692 767L438 487 692 225C700 217 708 204 708 187 708 171 704 154 692 142 675 129 663 125 646 125Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\" aria-label=\"Pr\u00f3ximo\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-eicon-chevron-right\" viewbox=\"0 0 1000 1000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M696 533C708 521 713 504 713 487 713 471 708 454 696 446L400 146C388 133 375 125 354 125 338 125 325 129 313 142 300 154 292 171 292 187 292 204 296 221 308 233L563 492 304 771C292 783 288 800 288 817 288 833 296 850 308 863 321 871 338 875 354 875 371 875 388 867 400 854L696 533Z\"><\/path><\/svg>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a22de77 e-flex e-con-boxed e-con e-parent\" data-id=\"a22de77\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-5492878 e-con-full e-flex e-con e-child\" data-id=\"5492878\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3e68df9 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"3e68df9\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:600}\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.cnshining.com\/wp-content\/uploads\/2024\/12\/120ml-Aluminum-Lotion-Pump-Bottles-1.0.jpg\" data-elementor-open-lightbox=\"yes\" data-elementor-lightbox-title=\"120ml-Aluminum-Lotion-Pump-Bottles-1.0\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MTg1OTksInVybCI6Imh0dHBzOlwvXC93d3cuY25zaGluaW5nLmNvbVwvd3AtY29udGVudFwvdXBsb2Fkc1wvMjAyNFwvMTJcLzEyMG1sLUFsdW1pbnVtLUxvdGlvbi1QdW1wLUJvdHRsZXMtMS4wLmpwZyJ9\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.cnshining.com\/wp-content\/uploads\/2024\/12\/120ml-Aluminum-Lotion-Pump-Bottles-1.0-1024x576.jpg\" class=\"attachment-large size-large wp-image-18599\" alt=\"Frascos de lo\u00e7\u00e3o de alum\u00ednio com bomba dosadora de 120ml - 1.0\" srcset=\"https:\/\/www.cnshining.com\/wp-content\/uploads\/2024\/12\/120ml-Aluminum-Lotion-Pump-Bottles-1.0-1024x576.jpg 1024w, https:\/\/www.cnshining.com\/wp-content\/uploads\/2024\/12\/120ml-Aluminum-Lotion-Pump-Bottles-1.0-300x169.jpg 300w, https:\/\/www.cnshining.com\/wp-content\/uploads\/2024\/12\/120ml-Aluminum-Lotion-Pump-Bottles-1.0-768x432.jpg 768w, https:\/\/www.cnshining.com\/wp-content\/uploads\/2024\/12\/120ml-Aluminum-Lotion-Pump-Bottles-1.0-18x10.jpg 18w, https:\/\/www.cnshining.com\/wp-content\/uploads\/2024\/12\/120ml-Aluminum-Lotion-Pump-Bottles-1.0-600x338.jpg 600w, https:\/\/www.cnshining.com\/wp-content\/uploads\/2024\/12\/120ml-Aluminum-Lotion-Pump-Bottles-1.0.jpg 1500w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" title=\"\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-03493cd e-con-full e-flex e-con e-child\" data-id=\"03493cd\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8f8cbb6 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"8f8cbb6\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Caracter\u00edsticas da Bomba de Lo\u00e7\u00e3o Premium<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a11dbc5 elementor-widget elementor-widget-text-editor\" data-id=\"a11dbc5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>O <strong>bomba de lo\u00e7\u00e3o<\/strong> anexado ao <strong>Frasco de alum\u00ednio de 120 ml<\/strong> Aprimora sua funcionalidade, oferecendo dosagem precisa e consistente. Fabricadas com materiais de alta qualidade, como alum\u00ednio, PP ou bambu, essas bombas est\u00e3o dispon\u00edveis com acabamentos canelado, liso, prateado brilhante ou dourado fosco. Os tamanhos de tampa incluem 18\/410, 20\/410, 24\/410 e 28\/410, garantindo compatibilidade com diversos tipos de frascos. O comprimento do tubo de imers\u00e3o e os estilos de corte \u2014 plano, angulado, em V ou chanfrado \u2014 podem ser personalizados para atender \u00e0s necessidades espec\u00edficas do produto. Com uma vaz\u00e3o de 1 cc a 2 cc por acionamento, esses dispensadores s\u00e3o vers\u00e1teis e confi\u00e1veis. Saiba mais sobre nossa linha premium.\u00a0<a href=\"https:\/\/www.cnshining.com\/pt\/bomba-de-locao\/\">op\u00e7\u00f5es de bomba de lo\u00e7\u00e3o<\/a>.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8d064b4 e-flex e-con-boxed e-con e-parent\" data-id=\"8d064b4\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1e54026 e-con-full e-flex e-con e-child\" data-id=\"1e54026\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-70d29bc elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"70d29bc\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:200}\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Escolha um fabricante de confian\u00e7a<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d67faa elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"3d67faa\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:400}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Como l\u00edder <strong>fabricante<\/strong> e <strong>fornecedor<\/strong>, Somos especializados na fabrica\u00e7\u00e3o de produtos de alta qualidade. <strong>Frascos de lo\u00e7\u00e3o com bomba dosadora de alum\u00ednio de 120ml<\/strong> Feito sob medida para atender \u00e0s suas necessidades. De materiais sustent\u00e1veis \u00e0 personaliza\u00e7\u00e3o avan\u00e7ada, oferecemos solu\u00e7\u00f5es que diferenciam sua marca. Visite nossa p\u00e1gina de produtos. <a href=\"https:\/\/www.cnshining.com\/pt\/produtos\/garrafa-de-bomba-de-locao-de-aluminio\/\">Embalagem de alum\u00ednio brilhante<\/a>\u00a0Comece sua jornada conosco hoje mesmo!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1a48c33 e-con-full e-flex e-con e-parent\" data-id=\"1a48c33\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-896635a elementor-widget elementor-widget-text-editor\" data-id=\"896635a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>\t\t<div data-elementor-type=\"container\" data-elementor-id=\"23182\" class=\"elementor elementor-23182\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6552a05d e-flex e-con-boxed e-con e-parent\" data-id=\"6552a05d\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-166f0495 e-con-full e-flex e-con e-child\" data-id=\"166f0495\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-7cb7f12f e-con-full e-flex e-con e-child\" data-id=\"7cb7f12f\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f1446a4 elementor-widget elementor-widget-heading\" data-id=\"f1446a4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Encontre mais bombas, pulverizadores e dispensadores.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-15f23a30 e-con-full e-flex e-con e-child\" data-id=\"15f23a30\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-5367171 e-con-full e-flex e-con e-child\" data-id=\"5367171\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-74cf9652 img elementor-cta--valign-bottom elementor-cta--skin-classic elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"74cf9652\" data-element_type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/www.cnshining.com\/wp-content\/uploads\/2024\/12\/fine-mist-pump-P201B.jpg);\" role=\"img\" aria-label=\"bomba-de-n\u00e9voa-fina-P201B\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-24a7c576 e-con-full e-flex e-con e-child\" data-id=\"24a7c576\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-684e1411 elementor-widget elementor-widget-text-editor\" data-id=\"684e1411\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/www.cnshining.com\/pt\/produtos\/frasco-de-spray-de-nevoa-fina-de-aluminio\/\" target=\"_blank\" rel=\"noopener\">Spray de n\u00e9voa fina \u2192<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2d22a082 e-con-full e-flex e-con e-child\" data-id=\"2d22a082\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2662c084 img elementor-cta--valign-bottom elementor-cta--skin-classic elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"2662c084\" data-element_type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/www.cnshining.com\/wp-content\/uploads\/2025\/11\/Trigger-Spray-T281G.webp);\" role=\"img\" aria-label=\"Spray de gatilho T281G\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1b7765bb e-con-full e-flex e-con e-child\" data-id=\"1b7765bb\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-97fc9aa elementor-widget elementor-widget-text-editor\" data-id=\"97fc9aa\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/www.cnshining.com\/pt\/produtos\/frasco-de-spray-de-aluminio\/\" target=\"_blank\" rel=\"noopener\">Spray de gatilho \u2192<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-20cbe50 e-con-full e-flex e-con e-child\" data-id=\"20cbe50\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-23318db8 img elementor-cta--valign-bottom elementor-cta--skin-classic elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"23318db8\" data-element_type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/www.cnshining.com\/wp-content\/uploads\/2025\/11\/Aluminum-Lotion-Pump-1.webp);\" role=\"img\" aria-label=\"Bomba de lo\u00e7\u00e3o de alum\u00ednio\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3f5e2856 e-con-full e-flex e-con e-child\" data-id=\"3f5e2856\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ced0ef0 elementor-widget elementor-widget-text-editor\" data-id=\"ced0ef0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/www.cnshining.com\/pt\/produtos\/garrafa-de-bomba-de-locao-de-aluminio\/\" target=\"_blank\" rel=\"noopener\">Bomba de lo\u00e7\u00e3o \u2192<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-73930ba4 e-con-full e-flex e-con e-child\" data-id=\"73930ba4\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-77f08f2a img elementor-cta--valign-bottom elementor-cta--skin-classic elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"77f08f2a\" data-element_type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/www.cnshining.com\/wp-content\/uploads\/2025\/07\/Treatment-Pump-1.webp);\" role=\"img\" aria-label=\"Bomba de tratamento\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-695b9a62 e-con-full e-flex e-con e-child\" data-id=\"695b9a62\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-510bc1fb elementor-widget elementor-widget-text-editor\" data-id=\"510bc1fb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/www.cnshining.com\/pt\/produtos\/garrafa-de-bomba-de-tratamento-de-aluminio\/\" target=\"_blank\" rel=\"noopener\">Bomba de tratamento \u2192<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f77c778 e-con-full e-flex e-con e-child\" data-id=\"f77c778\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ea8910d img elementor-cta--valign-bottom elementor-cta--skin-classic elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"ea8910d\" data-element_type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/www.cnshining.com\/wp-content\/uploads\/2025\/11\/Foam-Pump-5-1.webp);\" role=\"img\" aria-label=\"Bomba de espuma\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-31570c5 e-con-full e-flex e-con e-child\" data-id=\"31570c5\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-512e2b1 elementor-widget elementor-widget-text-editor\" data-id=\"512e2b1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/www.cnshining.com\/pt\/produtos\/garrafa-de-bomba-de-espuma-de-aluminio\/\" target=\"_blank\" rel=\"noopener\">Bomba de espuma \u2192<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9d70110 e-con-full e-flex e-con e-child\" data-id=\"9d70110\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2717483 img elementor-cta--valign-bottom elementor-cta--skin-classic elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"2717483\" data-element_type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/www.cnshining.com\/wp-content\/uploads\/2025\/11\/24mm-Aluminum-Screw-Cap.webp);\" role=\"img\" aria-label=\"Tampa de rosca de alum\u00ednio de 24 mm\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0cb1676 e-con-full e-flex e-con e-child\" data-id=\"0cb1676\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2149501 elementor-widget elementor-widget-text-editor\" data-id=\"2149501\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/www.cnshining.com\/pt\/produtos\/garrafa-de-aluminio-com-tampa-de-rosca\/\" target=\"_blank\" rel=\"noopener\">Caps \u2192<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Material: Alum\u00ednio 99.7% 1070A Volumes de Enchimento: 120ml ou 4oz Formato do Ombro: Redondo Tamanhos Dispon\u00edveis: \u03a635*150mm, \u03a640*120mm, \u03a645*100mm Op\u00e7\u00f5es de Rosca: 18\/410, 20\/410, 24\/410, 28\/410 Op\u00e7\u00f5es de Cores: Escovado, Preto, Branco, etc. Revestimento Interno: Poliimida, revestimentos \u00e0 base de poli\u00e9ster, revestimento interno livre de BPA; recomenda-se teste de compatibilidade Sistemas Dispensadores: Bomba de lo\u00e7\u00e3o Revestimentos Externos: Base branca ou transparente T\u00e9cnicas de Impress\u00e3o: Serigrafia, Transfer\u00eancia T\u00e9rmica, Impress\u00e3o Offset Personaliza\u00e7\u00e3o de Impress\u00e3o: At\u00e9 1-9 cores [\u2026]<\/p>","protected":false},"author":1,"featured_media":18599,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-18596","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/www.cnshining.com\/pt\/wp-json\/wp\/v2\/pages\/18596","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cnshining.com\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.cnshining.com\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.cnshining.com\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cnshining.com\/pt\/wp-json\/wp\/v2\/comments?post=18596"}],"version-history":[{"count":0,"href":"https:\/\/www.cnshining.com\/pt\/wp-json\/wp\/v2\/pages\/18596\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cnshining.com\/pt\/wp-json\/wp\/v2\/media\/18599"}],"wp:attachment":[{"href":"https:\/\/www.cnshining.com\/pt\/wp-json\/wp\/v2\/media?parent=18596"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}